{"id":736,"date":"2014-07-18T12:00:58","date_gmt":"2014-07-18T12:00:58","guid":{"rendered":"https:\/\/ferrolan.es\/blog\/?p=736"},"modified":"2025-10-30T15:02:55","modified_gmt":"2025-10-30T14:02:55","slug":"repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202","status":"publish","type":"post","link":"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/","title":{"rendered":"Repara tu sanitario y otras piezas de porcelana con nuestros consejos"},"content":{"rendered":"[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]Con el paso del tiempo los sanitarios pueden sufrir peque\u00f1os desperfectos. Es habitual que lavabos, bid\u00e9s o inodoros tengan peque\u00f1os desconchados, grietas o manchas de \u00f3xido. Por esta raz\u00f3n, para disfrutar de un sanitario en condiciones \u00f3ptimas es importante hacerle un buen mantenimiento o, en caso de accidente. reparar su superficie. Para esto \u00faltimo en Ferrolan disponemos de distintas soluciones para la reparaci\u00f3n de ba\u00f1eras, lavamanos o sanitarios. A\u00a0continuaci\u00f3n te mostramos los productos disponibles, los cu\u00e1les ser\u00e1n adecuados dependiendo del tipo de desperfecto que sufra la pieza a reparar.<\/p>\n<h2>Kit-Ker: reparador de golpes y desconchados<\/h2>\n<p>Sin duda alguna el desperfecto m\u00e1s habitual son los peque\u00f1os golpes o desconchados en la superficie de los sanitarios. Y por eso os traemos el reparador por excelencia de golpes y desconchados. Kit Ker es un reparador apto para superficies de cer\u00e1mica, esmalte y acr\u00edlicas con resultados perfectos. Contiene todos los elementos necesarios para dejar como nueva la superficie a reparar: 1 spray, 1 masilla, 1 endurecedor, 3 lijas y 1 esp\u00e1tula.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-1.jpg\" alt=\"\" \/><\/p>\n<h3>Instrucciones de uso del Kit-Ker<\/h3>\n<p>En primer lugar deber\u00e1s limpiar la superficie, asegur\u00e1ndote que est\u00e9 seca, limpia y libre de grasa. A continuaci\u00f3n, y con la ayuda de una esp\u00e1tula, deber\u00e1s mezclar la cantidad necesaria de producto y aplicarla sobre la superficie da\u00f1ada. Acto seguido deber\u00e1s lijar la zona reparada hasta que quede totalmente lisa. Por \u00faltimo, aplicar\u00e1s un spray para igualar el color con el tono original del sanitario. Recuerda que Kit-Ker est\u00e1 disponible en una gran variedad de colores.<\/p>\n<h2>Spray-Ker: para cambiar el color<\/h2>\n<p>Spray ideal para cambiar o unificar el color de la porcelana sanitaria. Apto para superficies met\u00e1licas, cer\u00e1micas, con esmalte, con recubrimiento en polvo y lacadas.\u00a0Es un barniz de reparaci\u00f3n s\u00f3lido, resistente a la temperatura, las salpicaduras y de larga duraci\u00f3n.\u00a0Se puede retocar o modificar el color, con un resultado perfecto, de radiadores, calentadores de agua, revestimientos, m\u00e1quinas de lavar, etc.\u00a0No apto para revestir ba\u00f1eras, fregaderos, inodoros o baldosas de suelo.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-spray-ppl.jpg\" alt=\"\" \/><\/p>\n<h2>Stick-Ker: l\u00e1piz reparador<\/h2>\n<p>El Stick-Ker es un l\u00e1piz reparador de peque\u00f1as marcas, grietas, rozaduras y defectos en la porcelana sanitaria de su cocina y ba\u00f1o.\u00a0Con este l\u00e1piz de reparaci\u00f3n todas las imperfecciones se reparan r\u00e1pida y f\u00e1cilmente. Es ideal para superficies cer\u00e1micas, de esmalte, acr\u00edlicas, de metal, de recubrimiento en polvo y superficies lacadas.<\/p>\n<h2><\/h2>\n<p><img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-stick-ppl.jpg\" alt=\"\" \/><\/p>\n<h2>Pulidor sanitario: para eliminar manchas<\/h2>\n<p>El Pulidor sanitario elimina de la porcelana sanitaria, sin rayar ni deteriorar, las manchas m\u00e1s dif\u00edciles. Manchas de \u00f3xido, marcas met\u00e1licas, restos de adhesivo, suciedad resistente, etc.\u00a0Es tambi\u00e9n ideal para limpiar los restos de cal que se van depositando entre las juntas de los azulejos, siendo apto para superficies cer\u00e1micas, esmaltadas o similares.<\/p>\n<p>Para conseguir un resultado \u00f3ptimo se debe humedecer con agua la zona a tratar y seguidamente aplicar el pulidor sanitario.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-pulidor-ppl.jpg\" alt=\"\" \/><\/p>\n<h2>Kit-Esp\u00e1tula Fugi: rejuntado profesional<\/h2>\n<p>Un pr\u00e1ctico juego de esp\u00e1tulas multifuncionales para eliminar el exceso de cualquier sellador flexible como silicona, acr\u00edlico, poliuretano\u2026 o eliminar rejuntados envejecidos gracias a los 16 bordes distintos de aplicaci\u00f3n.\u00a0Los diferentes bordes permiten adaptarse a cualquier superficie ya sea lisa, rugosa o con desniveles y a rincones de pared y esquinas.\u00a0El resultado es un rejuntado profesional. Adem\u00e1s permite corregir errores, volviendo a rejuntar donde sea necesario, aunque el sellado haya secado.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-fugi-colores.jpg\" alt=\"\" \/><\/p>\n<p>Para m\u00e1s informaci\u00f3n, pueden visitarnos en cualquiera de <a href=\"https:\/\/ferrolan.es\/content\/27-nuestras-tiendas\" target=\"_blank\" rel=\"noopener\"><strong>nuestras tiendas<\/strong><\/a>.[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-ppl.jpg\" loading=\"lazy\" alt=\"\"><br \/>\n                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-ppl-1.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 18pt; text-align: justify;\">Cu\u00e1ntas veces nos encontramos que, con el paso del tiempo, los sanitarios sufren peque\u00f1os desperfectos, desconchados, grietas, manchas de \u00f3xido, etc.<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 18pt; text-align: justify;\">En Ferrolan disponemos de soluciones para las distintas reparaciones de piezas como ba\u00f1eras, lavamanos o sanitarios, sin necesidad de grandes conocimientos y poder realizarlo nosotros mismos.<\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n te mostramos los productos disponibles, los cu\u00e1les ser\u00e1n adecuados dependiendo del tipo de desperfecto que sufra la pieza a reparar.<\/p>\n<h2>Kit-Ker: reparador de golpes y desconchados<\/h2>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-1.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<p style=\"text-align: justify;\">El reparador por excelencia de golpes y desconchados en ba\u00f1eras y sanitarios. Apto para superficies de cer\u00e1mica, esmalte y acr\u00edlicas con resultados perfectos. Contiene todos los elementos necesarios para dejar como nueva la superficie a reparar: 1 spray, 1 masilla, 1 endurecedor, 3 lijas y 1 esp\u00e1tula.<\/p>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-2.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<h3>Instrucciones de uso del Kit-Ker<\/h3>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-3.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<h2>Spray-Ker: para cambiar el color<\/h2>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-spray-ppl.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt;\">Spray ideal para cambiar o unificar el color de la porcelana sanitaria. Apto para superficies met\u00e1licas, cer\u00e1micas, con esmalte, con recubrimiento en polvo y lacadas.<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt;\">\u00a0<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt;\">Es un barniz de reparaci\u00f3n s\u00f3lido, resistente a la temperatura, las salpicaduras y de larga duraci\u00f3n.<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt;\">\u00a0<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt;\">Se puede retocar o modificar el color, con un resultado perfecto, de radiadores, calentadores de agua, revestimientos, m\u00e1quinas de lavar, etc.<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt;\">\u00a0<\/p>\n<p>No apto para revestir ba\u00f1eras, fregaderos, inodoros o baldosas de suelo.<\/p>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-spray-colores.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<h2>Stick-Ker: l\u00e1piz reparador<\/h2>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-stick-ppl.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; text-align: justify;\">El Stick-Ker es un l\u00e1piz reparador de peque\u00f1as marcas, grietas, rozaduras y defectos en la porcelana sanitaria de su cocina y ba\u00f1o.<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Con este l\u00e1piz de reparaci\u00f3n todas las imperfecciones se reparan r\u00e1pida y f\u00e1cilmente. Es ideal para superficies cer\u00e1micas, de esmalte, acr\u00edlicas, de metal, de recubrimiento en polvo y superficies lacadas.<\/p>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-stick-colores.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<h2>Pulidor sanitario: para eliminar manchas<\/h2>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-pulidor-ppl.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 18pt 0pt;\">El Pulidor sanitario elimina de la porcelana sanitaria, sin rayar ni deteriorar, las manchas m\u00e1s dif\u00edciles. Manchas de \u00f3xido, marcas met\u00e1licas, restos de adhesivo, suciedad resistente, etc.<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 18pt 0pt;\">Es tambi\u00e9n ideal para limpiar los restos de cal que se van depositando entre las juntas de los azulejos, siendo apto para superficies cer\u00e1micas, esmaltadas o similares.<\/p>\n<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 18pt;\">Para conseguir un resultado \u00f3ptimo se debe humedecer con agua la zona a tratar y seguidamente aplicar el pulidor sanitario.<\/p>\n<h2>Kit-Esp\u00e1tula Fugi: rejuntado profesional<\/h2>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-fugi-ppl.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 18pt; text-align: justify;\">Un pr\u00e1ctico juego de esp\u00e1tulas multifuncionales para eliminar el exceso de cualquier sellador flexible como silicona, acr\u00edlico, poliuretano\u2026 o eliminar rejuntados envejecidos gracias a los 16 bordes distintos de aplicaci\u00f3n.<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 18pt; text-align: justify;\">Los diferentes bordes permiten adaptarse a cualquier superficie ya sea lisa, rugosa o con desniveles y a rincones de pared y esquinas.<\/p>\n<p style=\"text-align: justify;\">El resultado es un rejuntado profesional. Adem\u00e1s permite corregir errores, volviendo a rejuntar donde sea necesario, aunque el sellado haya secado.<\/p>\n<p>                            <img decoding=\"async\" src=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/content\/kit-ker-fugi-colores.jpg\" loading=\"lazy\" alt=\"\">                                <\/p>\n<h2>V\u00eddeo reparaci\u00f3n de un desconchado<\/h2>\n<p>https:\/\/www.youtube.com\/watch?v=WUhQ456_J1w<\/p>\n<p>Para m\u00e1s informaci\u00f3n, pueden visitarnos en cualquiera de <a href=\"http:\/\/www.ferrolan.es\/tiendas\" target=\"_blank\" rel=\"noopener\"><strong>nuestras tiendas<\/strong><\/a>.<\/p>\n","protected":false},"author":2,"featured_media":9614,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1089,1085],"tags":[],"class_list":{"0":"post-736","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-aprende-con-nosotros","8":"category-consejos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u2705 Repara tu sanitario y otras piezas de porcelana con nuestros consejos - Ferrolan Blog<\/title>\n<meta name=\"description\" content=\"Te damos las claves y te guiamos para que repares tu sanitario o cualquier pieza de porcelana para que quede como nueva.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2705 Repara tu sanitario y otras piezas de porcelana con nuestros consejos - Ferrolan Blog\" \/>\n<meta property=\"og:description\" content=\"Te damos las claves y te guiamos para que repares tu sanitario o cualquier pieza de porcelana para que quede como nueva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferrolan Blog\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-18T12:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T14:02:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/2024\/02\/inauguracion-outlet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1417\" \/>\n\t<meta property=\"og:image:height\" content=\"939\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ferrolan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ferrolan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/\",\"url\":\"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/\",\"name\":\"\u2705 Repara tu sanitario y otras piezas de porcelana con nuestros consejos - Ferrolan Blog\",\"isPartOf\":{\"@id\":\"https:\/\/ferrolan.es\/blog\/#website\"},\"datePublished\":\"2014-07-18T12:00:58+00:00\",\"dateModified\":\"2025-10-30T14:02:55+00:00\",\"author\":{\"@id\":\"https:\/\/ferrolan.es\/blog\/#\/schema\/person\/5f821ed7b37d03887255cc1869b7bd54\"},\"description\":\"Te damos las claves y te guiamos para que repares tu sanitario o cualquier pieza de porcelana para que quede como nueva.\",\"breadcrumb\":{\"@id\":\"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ferrolan.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Repara tu sanitario y otras piezas de porcelana con nuestros consejos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ferrolan.es\/blog\/#website\",\"url\":\"https:\/\/ferrolan.es\/blog\/\",\"name\":\"Ferrolan Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ferrolan.es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ferrolan.es\/blog\/#\/schema\/person\/5f821ed7b37d03887255cc1869b7bd54\",\"name\":\"Ferrolan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ferrolan.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b149d5904395425b1d5615ad2b7afdd232b37e43a107dfe2e261cf16e3f852bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b149d5904395425b1d5615ad2b7afdd232b37e43a107dfe2e261cf16e3f852bb?s=96&d=mm&r=g\",\"caption\":\"Ferrolan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2705 Repara tu sanitario y otras piezas de porcelana con nuestros consejos - Ferrolan Blog","description":"Te damos las claves y te guiamos para que repares tu sanitario o cualquier pieza de porcelana para que quede como nueva.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/","og_locale":"es_ES","og_type":"article","og_title":"\u2705 Repara tu sanitario y otras piezas de porcelana con nuestros consejos - Ferrolan Blog","og_description":"Te damos las claves y te guiamos para que repares tu sanitario o cualquier pieza de porcelana para que quede como nueva.","og_url":"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/","og_site_name":"Ferrolan Blog","article_published_time":"2014-07-18T12:00:58+00:00","article_modified_time":"2025-10-30T14:02:55+00:00","og_image":[{"width":1417,"height":939,"url":"https:\/\/ferrolan.es\/blog\/wp-content\/uploads\/2024\/02\/inauguracion-outlet.jpg","type":"image\/jpeg"}],"author":"Ferrolan","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ferrolan","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/","url":"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/","name":"\u2705 Repara tu sanitario y otras piezas de porcelana con nuestros consejos - Ferrolan Blog","isPartOf":{"@id":"https:\/\/ferrolan.es\/blog\/#website"},"datePublished":"2014-07-18T12:00:58+00:00","dateModified":"2025-10-30T14:02:55+00:00","author":{"@id":"https:\/\/ferrolan.es\/blog\/#\/schema\/person\/5f821ed7b37d03887255cc1869b7bd54"},"description":"Te damos las claves y te guiamos para que repares tu sanitario o cualquier pieza de porcelana para que quede como nueva.","breadcrumb":{"@id":"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ferrolan.es\/blog\/repara-tu-sanitario-y-otras-piezas-de-porcelana-con-nuestros-consejos-n202\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ferrolan.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Repara tu sanitario y otras piezas de porcelana con nuestros consejos"}]},{"@type":"WebSite","@id":"https:\/\/ferrolan.es\/blog\/#website","url":"https:\/\/ferrolan.es\/blog\/","name":"Ferrolan Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ferrolan.es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ferrolan.es\/blog\/#\/schema\/person\/5f821ed7b37d03887255cc1869b7bd54","name":"Ferrolan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ferrolan.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b149d5904395425b1d5615ad2b7afdd232b37e43a107dfe2e261cf16e3f852bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b149d5904395425b1d5615ad2b7afdd232b37e43a107dfe2e261cf16e3f852bb?s=96&d=mm&r=g","caption":"Ferrolan"}}]}},"_links":{"self":[{"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/posts\/736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/comments?post=736"}],"version-history":[{"count":8,"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/posts\/736\/revisions"}],"predecessor-version":[{"id":4679,"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/posts\/736\/revisions\/4679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/media\/9614"}],"wp:attachment":[{"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/media?parent=736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/categories?post=736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ferrolan.es\/blog\/wp-json\/wp\/v2\/tags?post=736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}